{"id":2536,"date":"2020-12-08T17:00:11","date_gmt":"2020-12-08T16:00:11","guid":{"rendered":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg"},"modified":"2021-02-10T16:47:43","modified_gmt":"2021-02-10T15:47:43","slug":"castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2","status":"inherit","type":"attachment","link":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/","title":{"rendered":"Castalie&#8212;Vide-poche-rectangulaire&#8212;Bleu-2020-12-02-Compagnie-du-verre-265"},"author":5,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-2536","attachment","type-attachment","status-inherit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/\" \/>\n<meta property=\"og:site_name\" content=\"La Compagnie du Verre\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-10T15:47:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"875\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\\\/\",\"url\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\\\/\",\"name\":\"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/#website\"},\"datePublished\":\"2020-12-08T16:00:11+00:00\",\"dateModified\":\"2021-02-10T15:47:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Castalie&#8212;Vide-poche-rectangulaire&#8212;Bleu-2020-12-02-Compagnie-du-verre-265\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/\",\"name\":\"La Compagnie du Verre\",\"description\":\"L&#039;art du verre au service de la d\u00e9coration et de l&#039;architecture\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.compagnieduverre.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/","og_locale":"en_US","og_type":"article","og_title":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre","og_url":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/","og_site_name":"La Compagnie du Verre","article_modified_time":"2021-02-10T15:47:43+00:00","og_image":[{"width":875,"height":875,"url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/","url":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/","name":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265 - La Compagnie du Verre","isPartOf":{"@id":"https:\/\/www.compagnieduverre.com\/en\/#website"},"datePublished":"2020-12-08T16:00:11+00:00","dateModified":"2021-02-10T15:47:43+00:00","breadcrumb":{"@id":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.compagnieduverre.com\/en\/castalie-vide-poche-rectangulaire-bleu-2020-12-02-compagnie-du-verre-265-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.compagnieduverre.com\/en\/"},{"@type":"ListItem","position":2,"name":"Castalie&#8212;Vide-poche-rectangulaire&#8212;Bleu-2020-12-02-Compagnie-du-verre-265"}]},{"@type":"WebSite","@id":"https:\/\/www.compagnieduverre.com\/en\/#website","url":"https:\/\/www.compagnieduverre.com\/en\/","name":"La Compagnie du Verre","description":"L&#039;art du verre au service de la d\u00e9coration et de l&#039;architecture","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.compagnieduverre.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg 300w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg 150w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x600.jpg 600w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-768x768.jpg 768w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-100x100.jpg 100w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-140x140.jpg 140w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-500x500.jpg 500w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-350x350.jpg 350w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-800x800.jpg 800w, https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg 875w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":875,"height":875,"file":"2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg","filesize":62662,"sizes":{"woocommerce_thumbnail":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg","width":300,"height":300,"filesize":8410,"uncropped":false,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg","width":150,"height":150,"filesize":4062,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg"},"woocommerce_single":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x600.jpg","width":600,"height":600,"filesize":23842,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x600.jpg"},"medium":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg"},"thumbnail":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg"},"medium_large":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-768x768.jpg"},"portfolio-thumb_large":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x604.jpg","width":875,"height":604,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x604.jpg"},"portfolio-thumb":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x403.jpg","width":600,"height":403,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x403.jpg"},"portfolio-thumb_small":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-400x269.jpg","width":400,"height":269,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-400x269.jpg"},"portfolio-widget":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-100x100.jpg"},"nectar_small_square":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-140x140.jpg","width":140,"height":140,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-140x140.jpg"},"wide":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x500.jpg","width":875,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x500.jpg"},"wide_small":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-670x335.jpg","width":670,"height":335,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-670x335.jpg"},"regular":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-500x500.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-500x500.jpg"},"regular_small":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-350x350.jpg","width":350,"height":350,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-350x350.jpg"},"tall":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-500x875.jpg","width":500,"height":875,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-500x875.jpg"},"wide_photography":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x600.jpg","width":875,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x600.jpg"},"large_featured":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x770.jpg","width":875,"height":770,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-875x770.jpg"},"medium_featured":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-800x800.jpg","width":800,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-800x800.jpg"},"shop_catalog":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-300x300.jpg"},"shop_single":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x600.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-600x600.jpg"},"shop_thumbnail":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265-150x150.jpg"},"full":{"file":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg","width":875,"height":875,"mime_type":"image\/jpeg","source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"Colin Le Dorlot","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.compagnieduverre.com\/wp-content\/uploads\/2020\/12\/Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg","filename":"Castalie-Vide-poche-rectangulaire-Bleu-2020-12-02-Compagnie-du-verre-265.jpg","filesize":62662,"_links":{"self":[{"href":"https:\/\/www.compagnieduverre.com\/en\/wp-json\/wp\/v2\/media\/2536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compagnieduverre.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.compagnieduverre.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.compagnieduverre.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.compagnieduverre.com\/en\/wp-json\/wp\/v2\/comments?post=2536"}]}}